{"id":3471,"date":"2024-01-07T16:18:48","date_gmt":"2024-01-07T16:18:48","guid":{"rendered":"https:\/\/roelwijngaarden.com\/?page_id=3471"},"modified":"2024-03-01T21:46:31","modified_gmt":"2024-03-01T21:46:31","slug":"nieuw","status":"publish","type":"page","link":"https:\/\/roelwijngaarden.com\/index.php\/nieuw\/","title":{"rendered":"Nieuw!"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image alignleft size-full is-resized is-style-rounded wp-duotone-unset-1\"><a href=\"https:\/\/roelwijngaarden.com\/index.php\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"147\" src=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2023\/10\/catlogo_150px.png\" alt=\"site banner, afbeelding\" class=\"wp-image-155\" style=\"aspect-ratio:1.0204081632653061;object-fit:contain;width:68px;height:auto\"\/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"has-text-align-center\">Hier vindt je de laatste toegevoegde labels, zo&#8217;n 1 a 2 keer per jaar voeg ik de nieuwe aanwinsten toe aan de database. Dit kunnen labels zijn van het huidige jaar maar ook stokoude exemplaren.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/roelwijngaarden.com\/\">Terug naar Home.<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\"><\/h2>\n\n\n<style type=\"text\/css\">\n#foogallery-gallery-3437.fg-masonry .fg-item { width: 150px; }\n#foogallery-gallery-3437.fg-masonry { --fg-gutter: 40px; }<\/style>\n\t\t\t<div class=\"foogallery foogallery-container foogallery-masonry foogallery-lightbox-foobox fg-center fg-masonry fg-ready fg-dark fg-border-thin fg-loading-default fg-loaded-fade-in fg-caption-hover fg-hover-instant fg-hover-zoom2 fg-c-c fg-fixed\" id=\"foogallery-gallery-3437\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:false,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true,&quot;state&quot;:{&quot;enabled&quot;:true,&quot;mask&quot;:&quot;foogallery-{id}&quot;},&quot;template&quot;:{&quot;columnWidth&quot;:150,&quot;gutter&quot;:40}}\" style=\"--fg-title-line-clamp: 0; --fg-description-line-clamp: 0;\" >\n\t\t<div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1590.jpg\" data-caption-desc=\"A1590\" data-attachment-id=\"3599\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"330\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1590\/2957799127.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22330%22%20viewBox%3D%220%200%20150%20330%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">A1590<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1592.jpg\" data-caption-desc=\"Chinese Firecrackers\" data-attachment-id=\"3601\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"176\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1592\/2398527643.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22176%22%20viewBox%3D%220%200%20150%20176%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Chinese Firecrackers<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1591.jpg\" data-caption-desc=\"Superior Mandarin\" data-attachment-id=\"3600\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"110\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1591\/3945887023.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22110%22%20viewBox%3D%220%200%20150%20110%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Superior Mandarin<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1588.jpg\" data-caption-desc=\"Huan Chu\" data-attachment-id=\"3597\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"174\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1588\/1433472428.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22174%22%20viewBox%3D%220%200%20150%20174%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Huan Chu<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1589.jpg\" data-caption-desc=\"Lady Cracker\" data-attachment-id=\"3598\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"77\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1589\/1395700712.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%2277%22%20viewBox%3D%220%200%20150%2077%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Lady Cracker<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1586.jpg\" data-caption-desc=\"Extra Selected Ladycrackers\" data-attachment-id=\"3595\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"36\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1586\/1293663601.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%2236%22%20viewBox%3D%220%200%20150%2036%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Extra Selected Ladycrackers<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1587.jpg\" data-caption-desc=\"Tiger 1\" data-attachment-id=\"3596\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"191\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1587\/1729744215.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22191%22%20viewBox%3D%220%200%20150%20191%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Tiger 1<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1583.jpg\" data-caption-desc=\"Chooet Minas 305\" data-attachment-id=\"3593\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"179\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1583\/333075492.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22179%22%20viewBox%3D%220%200%20150%20179%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Chooet Minas 305<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1584.jpg\" data-caption-desc=\"Thunder Crackers\" data-attachment-id=\"3594\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"264\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1584\/3832965211.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22264%22%20viewBox%3D%220%200%20150%20264%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Thunder Crackers<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1581.jpg\" data-caption-desc=\"China Boller B\" data-attachment-id=\"3591\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"212\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1581\/1545597366.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22212%22%20viewBox%3D%220%200%20150%20212%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">China Boller B<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1582.jpg\" data-caption-desc=\"Yan Kee Boy\" data-attachment-id=\"3592\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"302\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1582\/876119789.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22302%22%20viewBox%3D%220%200%20150%20302%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Yan Kee Boy<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1577.jpg\" data-caption-desc=\"Color Firecrackers\" data-attachment-id=\"3588\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img fetchpriority=\"high\" decoding=\"async\" width=\"150\" height=\"612\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1577\/1827136142.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22612%22%20viewBox%3D%220%200%20150%20612%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Color Firecrackers<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1578.jpg\" data-caption-desc=\"Super Charged Flashlight Crackers\" data-attachment-id=\"3589\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"638\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1578\/1586438773.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22638%22%20viewBox%3D%220%200%20150%20638%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Super Charged Flashlight Crackers<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1580.jpg\" data-caption-desc=\"China Boller B\" data-attachment-id=\"3590\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"178\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1580\/2080187263.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22178%22%20viewBox%3D%220%200%20150%20178%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">China Boller B<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1575.jpg\" data-caption-desc=\"Successive Happy News 180s\" data-attachment-id=\"3586\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"1200\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1575.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%221200%22%20viewBox%3D%220%200%20150%201200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Successive Happy News 180s<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/A1576.jpg\" data-caption-desc=\"Nitrate 100 shots\" data-attachment-id=\"3587\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"35\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/A1576\/1789287626.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%2235%22%20viewBox%3D%220%200%20150%2035%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Nitrate 100 shots<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/D1595.jpg\" data-caption-desc=\"Baby Raketen Weissblinker\" data-attachment-id=\"3604\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"166\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/D1595\/3961080091.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22166%22%20viewBox%3D%220%200%20150%20166%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Baby Raketen Weissblinker<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/D1596.jpg\" data-caption-desc=\"Mini Raketen Silbercracker\" data-attachment-id=\"3605\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"196\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/D1596\/2313067695.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22196%22%20viewBox%3D%220%200%20150%20196%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Mini Raketen Silbercracker<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/D1597.jpg\" data-caption-desc=\"Mini Raketen Salut\" data-attachment-id=\"3606\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"196\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/D1597\/2749164681.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22196%22%20viewBox%3D%220%200%20150%20196%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Mini Raketen Salut<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/D1598.jpg\" data-caption-desc=\"Moon Travellers\" data-attachment-id=\"3607\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"237\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/D1598\/2444504178.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22237%22%20viewBox%3D%220%200%20150%20237%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Moon Travellers<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/C1593.jpg\" data-caption-desc=\"Jumping Jack\" data-attachment-id=\"3602\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"123\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/C1593\/1221545506.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22123%22%20viewBox%3D%220%200%20150%20123%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Jumping Jack<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/2025\/10\/C1594.jpg\" data-caption-desc=\"Multiplying Parachute by day\" data-attachment-id=\"3603\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"275\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/roelwijngaarden.com\/wp-content\/uploads\/cache\/2025\/10\/C1594\/2839713132.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22275%22%20viewBox%3D%220%200%20150%20275%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Multiplying Parachute by day<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Hier vindt je de laatste toegevoegde labels, zo&#8217;n 1 a 2 keer per jaar voeg ik de nieuwe aanwinsten toe aan de database. Dit kunnen labels zijn van het huidige jaar maar ook stokoude exemplaren. Terug naar Home.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3471","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/pages\/3471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/comments?post=3471"}],"version-history":[{"count":11,"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/pages\/3471\/revisions"}],"predecessor-version":[{"id":3512,"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/pages\/3471\/revisions\/3512"}],"wp:attachment":[{"href":"https:\/\/roelwijngaarden.com\/index.php\/wp-json\/wp\/v2\/media?parent=3471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}